{"id":2996,"date":"2017-01-09T13:22:30","date_gmt":"2017-01-09T13:22:30","guid":{"rendered":"http:\/\/test.armeemuseum.ch?page_id=2996"},"modified":"2017-02-02T14:56:12","modified_gmt":"2017-02-02T13:56:12","slug":"2996-2","status":"publish","type":"post","link":"https:\/\/armeemuseum.ch\/en\/2996-2\/","title":{"rendered":"Lehren aus dem Koreakrieg &#8211; Vorschau"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8221;section&#8221;][et_pb_row admin_label=&#8221;row&#8221;][et_pb_column type=&#8221;2_3&#8243;][et_pb_text admin_label=&#8221;Text&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<h2><strong>Die Lehren aus dem Koreakrieg f\u00fcr die Schweizer Armee<\/strong><\/h2>\n<h4>Vorschau auf den Vortrag vom 18. Januar 2017<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243;][et_pb_image admin_label=&#8221;Bild&#8221; src=&#8221;https:\/\/armeemuseum.ch\/wp-content\/uploads\/2016\/06\/Logo-VSAM-komprimiert-1.jpg&#8221; show_in_lightbox=&#8221;off&#8221; url_new_window=&#8221;off&#8221; use_overlay=&#8221;off&#8221; animation=&#8221;left&#8221; sticky=&#8221;off&#8221; align=&#8221;left&#8221; force_fullwidth=&#8221;off&#8221; always_center_on_mobile=&#8221;on&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;] [\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Zeile&#8221;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;Text&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p><strong>Im ersten Anlass der Vortragsreihe 2017 des Vereins Schweizer Armeemuseum (VSAM) werden Erkenntnisse aus dem Koreakrieg 1950-53 vermittelt. Dabei wird der Schwerpunkt auf die Lehren dieses Krieges f\u00fcr die Schweizer Armee gelegt.<\/strong><\/p>\n<p>Gleich mit einem hochkar\u00e4tigen Referat startet der Verein Schweizer Armeemuseum das neue Jahr. Gerhard Wyss als fundierter Kenner der milit\u00e4rischen Planungen der Schweizer Armee analysiert, wie der Koreakrieg von 1950-53 unsere Kriegsvorbereitungen beeinflusste. Der rund einst\u00fcndige Vortrag\u00a0wird nach einer allgemeinen Einf\u00fchrung in die Milit\u00e4rgeografie die Besonderheiten der Umwelt und Milit\u00e4rgeografie Koreas \u2013 welche f\u00fcr den Krieg entscheidend waren \u2013 darstellen. Ziel ist, die Kriegslehren, vor allem bez\u00fcglich des Einsatzes von Infanterie, Panzertruppen, Artillerie und Luftwaffe f\u00fcr die Schweizer Armee herausarbeiten. Der Vortrag ist allgemein verst\u00e4ndlich gehalten und bedarf keiner besonderen milit\u00e4rischen Kenntnisse. Auch f\u00fcr Kenner von Korea sollte er einige durchaus neue Erkenntnisse bieten.<\/p>\n<p><strong>Der Referent:<\/strong> Gerhard Wyss, ehemaliger Chef Sektion F\u00fchrungs- und Kampfbauten Untergruppe Operationen<\/p>\n<p><strong>Treffpunkt:<\/strong> Mittwoch, 18. Januar, 18.50 Uhr, Parkplatz Soldatenstube 3 Tannen an der Allmendstrasse Thun (Zuweisung der Parkpl\u00e4tze vor Ort) \u2013 Anreise vom Bahnhof Thun mit Buslinie 4 bis Haltestelle Kleine Allmend. Der Vortrag findet wie \u00fcblich im Filmsaal der Instandhaltungschule 50 in der AKLA statt.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Zeile&#8221;][et_pb_column type=&#8221;1_2&#8243;][et_pb_blurb admin_label=&#8221;Informationstext&#8221; title=&#8221;Im November\/Dezember 1950 litten beide Kriegsparteien unter arktischer K\u00e4lte, am Yalu ca. \u2013 35 Grad Celsius, und tiefem Schnee.&#8221; url_new_window=&#8221;off&#8221; use_icon=&#8221;off&#8221; icon_color=&#8221;#7EBEC5&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#7EBEC5&#8243; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#7EBEC5&#8243; image=&#8221;https:\/\/armeemuseum.ch\/wp-content\/uploads\/2017\/01\/Bild-Korea.jpg&#8221; icon_placement=&#8221;top&#8221; animation=&#8221;top&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_icon_font_size=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; body_line_height=&#8221;1em&#8221; custom_padding=&#8221;0px|||&#8221;] [\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243;][et_pb_blurb admin_label=&#8221;Informationstext&#8221; title=&#8221;Die milit\u00e4rstrategische Lage Koreas zwischen China im Norden, Russland im Nordosten und Japan im S\u00fcdosten f\u00fchrte dazu, dass das Land w\u00e4hrend Jahrhunderten, besonders im 20. Jahrhundert, zum Spielball dieser M\u00e4chte wurde.&#8221; url_new_window=&#8221;off&#8221; use_icon=&#8221;off&#8221; icon_color=&#8221;#7EBEC5&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#7EBEC5&#8243; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#7EBEC5&#8243; image=&#8221;https:\/\/armeemuseum.ch\/wp-content\/uploads\/2017\/01\/Karte-Korea.jpg&#8221; icon_placement=&#8221;top&#8221; animation=&#8221;top&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; use_icon_font_size=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; body_line_height=&#8221;2.8em&#8221;] [\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Lehren aus dem Koreakrieg f\u00fcr die Schweizer Armee Vorschau auf den Vortrag vom 18. Januar 2017 Im ersten Anlass der Vortragsreihe 2017 des Vereins Schweizer Armeemuseum (VSAM) werden Erkenntnisse aus dem Koreakrieg 1950-53 vermittelt. Dabei wird der Schwerpunkt auf die Lehren dieses Krieges f\u00fcr die Schweizer Armee gelegt. Gleich mit einem hochkar\u00e4tigen Referat startet [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[68],"tags":[],"class_list":["post-2996","post","type-post","status-publish","format-standard","hentry","category-news-2017"],"_links":{"self":[{"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/posts\/2996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/comments?post=2996"}],"version-history":[{"count":11,"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/posts\/2996\/revisions"}],"predecessor-version":[{"id":3007,"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/posts\/2996\/revisions\/3007"}],"wp:attachment":[{"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/media?parent=2996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/categories?post=2996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armeemuseum.ch\/en\/wp-json\/wp\/v2\/tags?post=2996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}